{"id":8945,"date":"2026-05-20T12:14:17","date_gmt":"2026-05-20T06:44:17","guid":{"rendered":"https:\/\/cpcindia.in\/?page_id=8945"},"modified":"2026-05-22T21:45:35","modified_gmt":"2026-05-22T16:15:35","slug":"pharma-medical","status":"publish","type":"page","link":"https:\/\/cpcindia.in\/ar\/pharma-medical\/","title":{"rendered":"Pharma &#038; Medical"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8945\" class=\"elementor elementor-8945\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7176370d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7176370d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-17394553\" data-id=\"17394553\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28bbf96f pt-90 pb-50 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28bbf96f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-688a4f62 pl-xl-70 pr-xl-70\" data-id=\"688a4f62\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11f8661e elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"11f8661e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Pharma &amp; Medical Equipment Disinfection Treatment<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f9b6eb elementor-widget elementor-widget-spacer\" data-id=\"9f9b6eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c136def elementor-widget elementor-widget-text-editor\" data-id=\"3c136def\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #ffffff;\">Precision-Driven Disinfection for Critical Healthcare &amp; Pharmaceutical Environments<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cd90325 elementor-widget elementor-widget-spacer\" data-id=\"2cd90325\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-18258c66 elementor-section-content-bottom align-self-end elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18258c66\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6e467177\" data-id=\"6e467177\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7f363c6e\" data-id=\"7f363c6e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-74d5993c\" data-id=\"74d5993c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-23f80c0c\" data-id=\"23f80c0c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a76521a elementor-widget elementor-widget-heading\" data-id=\"3a76521a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Request An Estimate<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bc3ff77 elementor-widget elementor-widget-shortcode\" data-id=\"7bc3ff77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f3224-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"3224\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ar\/wp-json\/wp\/v2\/pages\/8945#wpcf7-f3224-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"3224\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3224-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/><input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:3224,&quot;conditions&quot;:[{&quot;then_field&quot;:&quot;GENERALPESTCONTROLANNUAL&quot;,&quot;and_rules&quot;:[{&quot;if_field&quot;:&quot;menu-712&quot;,&quot;operator&quot;:&quot;equals&quot;,&quot;if_value&quot;:&quot;GENERAL PEST CONTROL (ANNUAL)&quot;}]},{&quot;then_field&quot;:&quot;TERMITES2YEARSWARRANTY&quot;,&quot;and_rules&quot;:[{&quot;if_field&quot;:&quot;menu-712&quot;,&quot;operator&quot;:&quot;equals&quot;,&quot;if_value&quot;:&quot;TERMITES (2 YEARS WARRANTY)&quot;}]},{&quot;then_field&quot;:&quot;BEDBUGSONETIME&quot;,&quot;and_rules&quot;:[{&quot;if_field&quot;:&quot;menu-712&quot;,&quot;operator&quot;:&quot;equals&quot;,&quot;if_value&quot;:&quot;BED BUGS (ONE TIME)&quot;}]},{&quot;then_field&quot;:&quot;LIZARDCONTROLANNUAL&quot;,&quot;and_rules&quot;:[{&quot;if_field&quot;:&quot;menu-712&quot;,&quot;operator&quot;:&quot;equals&quot;,&quot;if_value&quot;:&quot;LIZARD CONTROL (ANNUAL)&quot;}]},{&quot;then_field&quot;:&quot;RODENTSCONTROLANNUAL&quot;,&quot;and_rules&quot;:[{&quot;if_field&quot;:&quot;menu-712&quot;,&quot;operator&quot;:&quot;equals&quot;,&quot;if_value&quot;:&quot;RODENTS CONTROL(ANNUAL)&quot;}]},{&quot;then_field&quot;:&quot;DISINFECTIONTREATMENTONETIME&quot;,&quot;and_rules&quot;:[{&quot;if_field&quot;:&quot;menu-712&quot;,&quot;operator&quot;:&quot;equals&quot;,&quot;if_value&quot;:&quot;DISINFECTION TREATMENT (ONETIME)&quot;}]},{&quot;then_field&quot;:&quot;TICKSFLEASONETIME&quot;,&quot;and_rules&quot;:[{&quot;if_field&quot;:&quot;menu-712&quot;,&quot;operator&quot;:&quot;equals&quot;,&quot;if_value&quot;:&quot;TICKS &amp; FLEAS (ONE TIME)&quot;}]}],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:200,&quot;animation_outtime&quot;:200,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:false}}\" \/><input type=\"hidden\" name=\"_uacf7_hidden_conditional_fields\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"uacf7-form-wrapper-container uacf7-form-3224  \"><div class=\"row\">\n\n<div class=\"col-lg-6\">\n <label>Name * <\/label>\n <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Enter Name\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n<\/div>\n<div class=\"col-lg-6\">\n <label>Phone * <\/label>\n <span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"01061245741\" value=\"\" type=\"tel\" name=\"your-phone\" \/><\/span>\n<\/div>\n\n<div class=\"col-lg-6\">\n <label> Select Service\n<span class=\"wpcf7-form-control-wrap\" data-name=\"menu-712\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"menu-712\"><option value=\"GENERAL PEST CONTROL (ANNUAL)\">GENERAL PEST CONTROL (ANNUAL)<\/option><option value=\"TERMITES (2 YEARS WARRANTY)\">TERMITES (2 YEARS WARRANTY)<\/option><option value=\"BED BUGS (ONE TIME)\">BED BUGS (ONE TIME)<\/option><option value=\"LIZARD CONTROL (ANNUAL)\">LIZARD CONTROL (ANNUAL)<\/option><option value=\"RODENTS CONTROL(ANNUAL)\">RODENTS CONTROL(ANNUAL)<\/option><option value=\"DISINFECTION TREATMENT (ONETIME)\">DISINFECTION TREATMENT (ONETIME)<\/option><option value=\"TICKS &amp; FLEAS (ONE TIME)\">TICKS &amp; FLEAS (ONE TIME)<\/option><option value=\"DUCT CLEANING\">DUCT CLEANING<\/option><\/select><\/span>\n<\/label>\n\n<\/div>\n<div class=\"col-lg-6\">\n <label>Select Price\n<\/label>\n<div data-id=\"GENERALPESTCONTROLANNUAL\" data-orig_data_id=\"GENERALPESTCONTROLANNUAL\"  class=\"\" data-class=\"wpcf7cf_group\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"menu-883\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"menu-883\"><option value=\"1BHK- RS. 5,000\/-\">1BHK- RS. 5,000\/-<\/option><option value=\"2BHK-RS. 6000\/-\">2BHK-RS. 6000\/-<\/option><option value=\"3BHK-Rs. 6800\/-\">3BHK-Rs. 6800\/-<\/option><option value=\"4BHK-Rs. 7750\/-\">4BHK-Rs. 7750\/-<\/option><option value=\"5BHK-Rs. 8600\/-\">5BHK-Rs. 8600\/-<\/option><\/select><\/span>\n<\/div>\n<div data-id=\"TERMITES2YEARSWARRANTY\" data-orig_data_id=\"TERMITES2YEARSWARRANTY\"  class=\"\" data-class=\"wpcf7cf_group\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"menu-733\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"menu-733\"><option value=\"1BHK-5000\/-\">1BHK-5000\/-<\/option><option value=\"2BHK- RS. 6000\">2BHK- RS. 6000<\/option><option value=\"3BHK-RS. 6800\/-\">3BHK-RS. 6800\/-<\/option><option value=\"4BHK-Rs. 7865\/-\">4BHK-Rs. 7865\/-<\/option><option value=\"5BHK-Rs. 9145\/-\">5BHK-Rs. 9145\/-<\/option><\/select><\/span>\n<\/div>\n<div data-id=\"BEDBUGSONETIME\" data-orig_data_id=\"BEDBUGSONETIME\"  class=\"\" data-class=\"wpcf7cf_group\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"menu-399\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"menu-399\"><option value=\"1BHK - 3540\/-\">1BHK - 3540\/-<\/option><option value=\"2BHK-4425\/-\">2BHK-4425\/-<\/option><option value=\"3BHK-5605\/-\">3BHK-5605\/-<\/option><option value=\"4BHK-6490\/-\">4BHK-6490\/-<\/option><option value=\"5BHK-7600\/-\">5BHK-7600\/-<\/option><\/select><\/span>\n<\/div>\n<div data-id=\"LIZARDCONTROLANNUAL\" data-orig_data_id=\"LIZARDCONTROLANNUAL\"  class=\"\" data-class=\"wpcf7cf_group\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"menu-378\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"menu-378\"><option value=\"1BHK- 5500\/-\">1BHK- 5500\/-<\/option><option value=\"2BHK-7080\/-\">2BHK-7080\/-<\/option><option value=\"3BHK-8260\/-\">3BHK-8260\/-<\/option><option value=\"4BHK-9440\/-\">4BHK-9440\/-<\/option><option value=\"5BHK-10325\/-\">5BHK-10325\/-<\/option><\/select><\/span>\n<\/div>\n<div data-id=\"RODENTSCONTROLANNUAL\" data-orig_data_id=\"RODENTSCONTROLANNUAL\"  class=\"\" data-class=\"wpcf7cf_group\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"menu-588\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"menu-588\"><option value=\"1BHK-5000\/-\">1BHK-5000\/-<\/option><option value=\"2BHK-6000\/-\">2BHK-6000\/-<\/option><option value=\"3BHK-6900\/-\">3BHK-6900\/-<\/option><option value=\"4BHK-7740\/-\">4BHK-7740\/-<\/option><option value=\"5BHK-8600\/-\">5BHK-8600\/-<\/option><\/select><\/span>\n<\/div>\n\n<div data-id=\"DISINFECTIONTREATMENTONETIME\" data-orig_data_id=\"DISINFECTIONTREATMENTONETIME\"  class=\"\" data-class=\"wpcf7cf_group\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"menu-374\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"menu-374\"><option value=\"1BHK-1770\/-\">1BHK-1770\/-<\/option><option value=\"2BHK-2950\/-\">2BHK-2950\/-<\/option><option value=\"3BHK-4425\/-\">3BHK-4425\/-<\/option><option value=\"4BHK-5310\/-\">4BHK-5310\/-<\/option><option value=\"5BHK-6195\/-\">5BHK-6195\/-<\/option><\/select><\/span>\n<\/div>\n<div data-id=\"TICKSFLEASONETIME\" data-orig_data_id=\"TICKSFLEASONETIME\"  class=\"\" data-class=\"wpcf7cf_group\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"menu-569\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"menu-569\"><option value=\"1BHK-RS. 5000\/-\">1BHK-RS. 5000\/-<\/option><option value=\"2BHK- RS. 5500\/-\">2BHK- RS. 5500\/-<\/option><option value=\"3BHK-RS.6100\/-\">3BHK-RS.6100\/-<\/option><option value=\"4BHK-6900\/-\">4BHK-6900\/-<\/option><option value=\"5BHK-7600\/-\">5BHK-7600\/-<\/option><\/select><\/span>\n<\/div>\n\n<\/div>\n<div class=\"col-lg-6\">\n <label>Email * <\/label>\n <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Enter Email Id\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/div>\n\n<div class=\"col-lg-6\">\n <label>City *  <\/label>\n <span class=\"wpcf7-form-control-wrap\" data-name=\"city\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Enter City\" value=\"\" type=\"text\" name=\"city\" \/><\/span>\n<\/div>\n\n<div class=\"col-12\">\n <label>Additional Details  <\/label>\n <span class=\"wpcf7-form-control-wrap\" data-name=\"AdditionalDetails\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Text here\" name=\"AdditionalDetails\"><\/textarea><\/span>\n<\/div>\n\n<div class=\"col-lg-6\">\n<br>\n <div id=\"cf7sr-6a983e8eb94ca\" class=\"cf7sr-g-recaptcha\" data-theme=\"light\" data-type=\"image\" data-size=\"normal\" data-sitekey=\"6Lcm_M4qAAAAAJx4otc25aqzPNyeGafFc5i7ZeaZ\"><\/div><span class=\"wpcf7-form-control-wrap cf7sr-recaptcha\" data-name=\"cf7sr-recaptcha\"><input type=\"hidden\" name=\"cf7sr-recaptcha\" value=\"\" class=\"wpcf7-form-control\"><\/span> \n<\/div>\n\n<div class=\"col-12 mt-15\">\n <div class=\"cms-submit\"><button class=\"wpcf7-form-control wpcf7-submit btn btn-primary btn-hover-secondary text-start btn-xl w-40\" type=\"submit\"><span class=\"cms-btn-content\"><span class=\"wpcf7-submit-icon cms-btn-icon cmsi cmsi-arrow-right rtl-flip\"><\/span><span class=\"cms-btn-text\">Submit Request<\/span><\/span><\/button><\/div>\n<\/div>\n<\/div><\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"22\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eac2b60 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eac2b60\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ea307d0\" data-id=\"ea307d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e04f6fb elementor-widget elementor-widget-image\" data-id=\"e04f6fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/cpcindia.in\/wp-content\/uploads\/2026\/05\/Advanced_-Disinfection-Solutions-3.avif\" class=\"attachment-full size-full wp-image-8973\" alt=\"\" srcset=\"https:\/\/cpcindia.in\/wp-content\/uploads\/2026\/05\/Advanced_-Disinfection-Solutions-3.avif 1200w, https:\/\/cpcindia.in\/wp-content\/uploads\/2026\/05\/Advanced_-Disinfection-Solutions-3-120x80.avif 120w, https:\/\/cpcindia.in\/wp-content\/uploads\/2026\/05\/Advanced_-Disinfection-Solutions-3-18x12.avif 18w, https:\/\/cpcindia.in\/wp-content\/uploads\/2026\/05\/Advanced_-Disinfection-Solutions-3-750x500.avif 750w, https:\/\/cpcindia.in\/wp-content\/uploads\/2026\/05\/Advanced_-Disinfection-Solutions-3-600x400.avif 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f3f6320\" data-id=\"f3f6320\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff8c912 elementor-widget elementor-widget-heading\" data-id=\"ff8c912\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Advanced Disinfection Solutions for Sensitive Environments<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04e978f elementor-widget elementor-widget-text-editor\" data-id=\"04e978f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>At CPC India, we deliver specialised disinfection and microbial decontamination solutions tailored for pharmaceutical facilities, laboratories, healthcare institutions, diagnostic centres, and sensitive medical equipment environments.<\/p><p>\u00a0<\/p><p>Our treatment protocols are designed to support hygienic integrity, contamination control, and operational safety across high-risk spaces.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e70bc30 elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"e70bc30\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-744041b\" data-id=\"744041b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78c2fdd elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"78c2fdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Designed for Critical &amp; Sterile Environments<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4470d37 elementor-widget elementor-widget-spacer\" data-id=\"4470d37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-142b367 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"142b367\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Supporting healthcare and pharmaceutical industries with structured, high-efficacy microbial control solutions.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39a299b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39a299b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65a71c6\" data-id=\"65a71c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1626aa5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1626aa5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b896094\" data-id=\"b896094\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2c0c3cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c0c3cc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4dba192\" data-id=\"4dba192\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b49e272 elementor-widget elementor-widget-heading\" data-id=\"b49e272\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Pharmaceutical Manufacturing Areas<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-433fd15\" data-id=\"433fd15\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2fc552b elementor-widget elementor-widget-heading\" data-id=\"2fc552b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Clean Rooms &amp; Sterile Environments<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-09c3b90\" data-id=\"09c3b90\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f59229a elementor-widget elementor-widget-heading\" data-id=\"f59229a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Diagnostic Laboratories<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-006e440\" data-id=\"006e440\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c26e9e elementor-widget elementor-widget-heading\" data-id=\"1c26e9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Medical Storage Facilities<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b4cee95 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4cee95\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-571dc57\" data-id=\"571dc57\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-afc9326 elementor-widget elementor-widget-heading\" data-id=\"afc9326\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Medical Equipment Handling Zones<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-802999f\" data-id=\"802999f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-524196f elementor-widget elementor-widget-heading\" data-id=\"524196f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">High-Touch Surfaces &amp; Workstations<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1a55a67\" data-id=\"1a55a67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c5eb28 elementor-widget elementor-widget-heading\" data-id=\"8c5eb28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">OT &amp; ICU Environments<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-35141c8\" data-id=\"35141c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-584bdad elementor-widget elementor-widget-heading\" data-id=\"584bdad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Air Handling &amp; Circulation Areas<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18b178c elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"18b178c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f19a1ad\" data-id=\"f19a1ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e928421 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"e928421\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Hospital-Grade Disinfection Protocols<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab34755 elementor-widget elementor-widget-spacer\" data-id=\"ab34755\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9daab6a elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"9daab6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>ULV Fogging, Surface Disinfection &amp; Targeted Microbial Treatment<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d593c4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d593c4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-899c480\" data-id=\"899c480\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34c88a1 elementor-widget elementor-widget-heading\" data-id=\"34c88a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Our Treatment Approach<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6c95298 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c95298\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2f262fc\" data-id=\"2f262fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-95dcfb9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"95dcfb9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ac949d9\" data-id=\"ac949d9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a19b78 elementor-widget elementor-widget-heading\" data-id=\"5a19b78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Surface disinfection using hospital-grade formulations<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-27ab490\" data-id=\"27ab490\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19b51aa elementor-widget elementor-widget-heading\" data-id=\"19b51aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">ULV fogging &amp; misting for broad-spectrum microbial control<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e98ada0\" data-id=\"e98ada0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ec02af elementor-widget elementor-widget-heading\" data-id=\"4ec02af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Targeted treatment for bacteria, viruses, fungi &amp; pathogens\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ff1e87c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ff1e87c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-cd9503b\" data-id=\"cd9503b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0def1f7 elementor-widget elementor-widget-heading\" data-id=\"0def1f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Non-corrosive application protocols suitable for sensitive environments<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6c9aaa6\" data-id=\"6c9aaa6\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dffd6d0 elementor-widget elementor-widget-heading\" data-id=\"dffd6d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Scheduled preventive disinfection programs for ongoing protection\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8cf3aa4\" data-id=\"8cf3aa4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5794fac elementor-widget elementor-widget-heading\" data-id=\"5794fac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Compliance-oriented hygiene support for regulated industries<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f0759ba elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"f0759ba\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-db1124c\" data-id=\"db1124c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95cad33 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"95cad33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Protection Beyond Cleaning\n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89aae06 elementor-widget elementor-widget-spacer\" data-id=\"89aae06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-358c2b8 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"358c2b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<section class=\"mid-banner banner-4\"><div class=\"banner-inner\"><p>Safeguarding product integrity, patient safety &amp; operational continuity.<\/p><\/div><\/section>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc54a4e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc54a4e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bf4ab00\" data-id=\"bf4ab00\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c7647d elementor-widget elementor-widget-heading\" data-id=\"0c7647d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Why CPC India<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-901df18 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"901df18\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-349b9e5\" data-id=\"349b9e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a41576 elementor-widget elementor-widget-heading\" data-id=\"4a41576\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Over 40 years of operational expertise<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0961e7d\" data-id=\"0961e7d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0adb728 elementor-widget elementor-widget-heading\" data-id=\"0adb728\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Trusted by corporates, institutions &amp; industrial facilities<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-eb2ed7d\" data-id=\"eb2ed7d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3589a2 elementor-widget elementor-widget-heading\" data-id=\"b3589a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Trained technical workforce with specialised treatment SOPs<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-338d08f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"338d08f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fe791b0\" data-id=\"fe791b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-91ce4a7 elementor-widget elementor-widget-heading\" data-id=\"91ce4a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Minimal operational disruption during treatment execution\n<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e73f532\" data-id=\"e73f532\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68b04ff elementor-widget elementor-widget-heading\" data-id=\"68b04ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Customised treatment plans based on site sensitivity and risk exposure<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-609751f elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"609751f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-67dac67\" data-id=\"67dac67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-330aaba elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"330aaba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Critical Hygiene Solutions for Sensitive Environments<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0da1a48 elementor-widget elementor-widget-spacer\" data-id=\"0da1a48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-afedbf9 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"afedbf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<section class=\"mid-banner banner-4\"><div class=\"banner-inner\"><p>CPC India delivers structured, professional disinfection solutions engineered for environments where hygiene standards cannot be compromised.<\/p><\/div><\/section>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2767bb elementor-widget elementor-widget-spacer\" data-id=\"c2767bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41f4fea elementor-align-center elementor-widget elementor-widget-button\" data-id=\"41f4fea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/cpcindia.in\/request-an-estimate\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Request An Estimate<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c1b1b73 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c1b1b73\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-09b64ce\" data-id=\"09b64ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc48492 elementor-widget elementor-widget-heading\" data-id=\"cc48492\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ideal For<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3891971 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3891971\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-cc74583\" data-id=\"cc74583\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5341df7 elementor-widget elementor-widget-heading\" data-id=\"5341df7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Pharmaceutical companies\n<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-dbcb434\" data-id=\"dbcb434\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70b4ceb elementor-widget elementor-widget-heading\" data-id=\"70b4ceb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Hospitals &amp; healthcare chains\n<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-58e8128\" data-id=\"58e8128\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9865ab8 elementor-widget elementor-widget-heading\" data-id=\"9865ab8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Diagnostic labs\n<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8bd4395 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8bd4395\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-890f329\" data-id=\"890f329\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d10f8c elementor-widget elementor-widget-heading\" data-id=\"9d10f8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Medical device companies\n<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ad4d893\" data-id=\"ad4d893\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9dde3f6 elementor-widget elementor-widget-heading\" data-id=\"9dde3f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Research facilities\n<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fb5ee9f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb5ee9f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-63202c0\" data-id=\"63202c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-727bfc6 elementor-widget elementor-widget-heading\" data-id=\"727bfc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Warehousing &amp; cold-chain facilities\n<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-55f3177\" data-id=\"55f3177\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b05fdb9 elementor-widget elementor-widget-heading\" data-id=\"b05fdb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Clinics &amp; rehabilitation centres\n<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pharma &amp; Medical Equipment Disinfection Treatment Precision-Driven Disinfection for Critical Healthcare &amp; Pharmaceutical Environments Request An Estimate Advanced Disinfection Solutions for Sensitive Environments At CPC India, we deliver specialised disinfection and microbial decontamination solutions tailored for pharmaceutical facilities, laboratories, healthcare institutions, diagnostic centres, and sensitive medical equipment environments. \u00a0 Our treatment protocols are designed to [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8945","page","type-page","status-publish","hentry","cms-has-post-thumbnail"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cpcindia.in\/ar\/wp-json\/wp\/v2\/pages\/8945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpcindia.in\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cpcindia.in\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cpcindia.in\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cpcindia.in\/ar\/wp-json\/wp\/v2\/comments?post=8945"}],"version-history":[{"count":9,"href":"https:\/\/cpcindia.in\/ar\/wp-json\/wp\/v2\/pages\/8945\/revisions"}],"predecessor-version":[{"id":8986,"href":"https:\/\/cpcindia.in\/ar\/wp-json\/wp\/v2\/pages\/8945\/revisions\/8986"}],"wp:attachment":[{"href":"https:\/\/cpcindia.in\/ar\/wp-json\/wp\/v2\/media?parent=8945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}